﻿{"id":14334,"date":"2017-10-03T09:24:39","date_gmt":"2017-10-03T07:24:39","guid":{"rendered":"https:\/\/www.lab23.it\/portfolio-items\/asm-venezia\/"},"modified":"2017-10-04T11:41:11","modified_gmt":"2017-10-04T09:41:11","slug":"asm-venezia","status":"publish","type":"avada_portfolio","link":"https:\/\/www.lab23.it\/fr\/portfolio-items\/asm-venezia\/","title":{"rendered":"ASM VENISE"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-bottom:55px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-two\"><h2 class=\"fusion-title-heading title-heading-center\" style=\"margin:0;\">ASM VENISE<\/h2><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator\" style=\"margin-left: auto;margin-right: auto;margin-bottom:31px;width:100%;max-width:30px;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#999999;border-color:#999999;border-top-width:2px;\"><\/div><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:25px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_2_3 2_3 fusion-two-third fusion-column-first\" style=\"--awb-bg-size:cover;width:65.3333%; margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"awb-gallery-wrapper awb-gallery-wrapper-1 button-span-no\"><div style=\"margin:-5px;--awb-bordersize:0px;\" class=\"fusion-gallery fusion-gallery-container fusion-grid-3 fusion-columns-total-4 fusion-gallery-layout-masonry fusion-gallery-1\"><div class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none fusion-grid-sizer\"><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none fusion-element-portrait\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-4.jpg\"><div style=\"background-image:url(https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-4.jpg);padding-top:calc((100% + 10px) * 1.6);\" class=\"fusion-masonry-element-container\"><img decoding=\"async\" src=\"https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-4.jpg\" width=\"1063\" height=\"1600\" alt=\"\" title=\"asm venezia 4\" aria-label=\"asm venezia 4\" class=\"img-responsive wp-image-13744\" srcset=\"https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-4-200x301.jpg 200w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-4-400x602.jpg 400w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-4-600x903.jpg 600w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-4-800x1204.jpg 800w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-4.jpg 1063w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 363px, (min-width: 712px) 545px, (min-width: 640px) 712px, \" \/><\/div><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none fusion-element-grid\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-6.jpg\"><div style=\"background-image:url(https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-6.jpg);padding-top:calc((100% + 10px) * 0.8 - 5px);\" class=\"fusion-masonry-element-container\"><img decoding=\"async\" src=\"https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-6.jpg\" width=\"1600\" height=\"1063\" alt=\"\" title=\"asm venezia 6\" aria-label=\"asm venezia 6\" class=\"img-responsive wp-image-13750\" srcset=\"https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-6-200x133.jpg 200w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-6-400x266.jpg 400w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-6-600x399.jpg 600w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-6-800x532.jpg 800w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-6-1200x797.jpg 1200w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-6.jpg 1600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 363px, (min-width: 712px) 545px, (min-width: 640px) 712px, \" \/><\/div><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none fusion-element-portrait\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-5.jpg\"><div style=\"background-image:url(https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-5.jpg);padding-top:calc((100% + 10px) * 1.6);\" class=\"fusion-masonry-element-container\"><img decoding=\"async\" src=\"https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-5.jpg\" width=\"1048\" height=\"1600\" alt=\"\" title=\"asm venezia 5\" aria-label=\"asm venezia 5\" class=\"img-responsive wp-image-13747\" srcset=\"https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-5-200x305.jpg 200w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-5-400x611.jpg 400w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-5-600x916.jpg 600w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-5-800x1221.jpg 800w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm-venezia-5.jpg 1048w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 363px, (min-width: 712px) 545px, (min-width: 640px) 712px, \" \/><\/div><\/a><\/div><\/div><div style=\"padding:5px;\" class=\"fusion-grid-column fusion-gallery-column fusion-gallery-column-3 hover-type-none fusion-element-grid\"><div class=\"fusion-gallery-image\"><a href=\"https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm_venezia_3.jpg\"><div style=\"background-image:url(https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm_venezia_3.jpg);padding-top:calc((100% + 10px) * 0.8 - 5px);\" class=\"fusion-masonry-element-container\"><img decoding=\"async\" src=\"https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm_venezia_3.jpg\" width=\"1600\" height=\"1063\" alt=\"\" title=\"asm_venezia_3\" aria-label=\"asm_venezia_3\" class=\"img-responsive wp-image-13759\" srcset=\"https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm_venezia_3-200x133.jpg 200w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm_venezia_3-400x266.jpg 400w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm_venezia_3-600x399.jpg 600w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm_venezia_3-800x532.jpg 800w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm_venezia_3-1200x797.jpg 1200w, https:\/\/www.lab23.it\/wp-content\/uploads\/2017\/10\/asm_venezia_3.jpg 1600w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 363px, (min-width: 712px) 545px, (min-width: 640px) 712px, \" \/><\/div><\/a><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-last\" style=\"--awb-bg-size:cover;width:30.6666%;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-two\"><h2 class=\"fusion-title-heading title-heading-left\" style=\"margin:0;\">D\u00e9tails du projet<\/h2><\/div><div class=\"fusion-text fusion-text-1\"><p><b>Ann\u00e9e:<\/b> 2011<\/p>\n<p><strong>Client:\u00a0<\/strong>ASM SPA &#8211; Venise, Italie<\/p>\n<p><strong>Produits:<\/strong>\u00a0Avo corbeille, Horizon si\u00e8ge, D-planter banquette\/jardiniere<\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:40px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\"><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-bottom:40px;width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1261,"featured_media":13934,"menu_order":13,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[144],"portfolio_skills":[],"portfolio_tags":[],"class_list":["post-14334","avada_portfolio","type-avada_portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-projets"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lab23.it\/fr\/wp-json\/wp\/v2\/avada_portfolio\/14334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lab23.it\/fr\/wp-json\/wp\/v2\/avada_portfolio"}],"about":[{"href":"https:\/\/www.lab23.it\/fr\/wp-json\/wp\/v2\/types\/avada_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.lab23.it\/fr\/wp-json\/wp\/v2\/users\/1261"}],"version-history":[{"count":0,"href":"https:\/\/www.lab23.it\/fr\/wp-json\/wp\/v2\/avada_portfolio\/14334\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lab23.it\/fr\/wp-json\/wp\/v2\/media\/13934"}],"wp:attachment":[{"href":"https:\/\/www.lab23.it\/fr\/wp-json\/wp\/v2\/media?parent=14334"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/www.lab23.it\/fr\/wp-json\/wp\/v2\/portfolio_category?post=14334"},{"taxonomy":"portfolio_skills","embeddable":true,"href":"https:\/\/www.lab23.it\/fr\/wp-json\/wp\/v2\/portfolio_skills?post=14334"},{"taxonomy":"portfolio_tags","embeddable":true,"href":"https:\/\/www.lab23.it\/fr\/wp-json\/wp\/v2\/portfolio_tags?post=14334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}